{"id":391,"date":"2020-09-03T23:52:17","date_gmt":"2020-09-03T21:52:17","guid":{"rendered":"http:\/\/www.tamboerke.nl\/?p=391"},"modified":"2020-09-03T23:52:17","modified_gmt":"2020-09-03T21:52:17","slug":"gerestaureerd-en-minitrommeltje","status":"publish","type":"post","link":"http:\/\/www.tamboerke.nl\/index.php\/2020\/09\/03\/gerestaureerd-en-minitrommeltje\/","title":{"rendered":"Gerestaureerd en minitrommeltje"},"content":{"rendered":"\n<p>We hebben 2 trommen, 1 senior en 1 junior, gerestaureerd voor het Gilde St.Antonius St.Sebastiaan uit Udenhout. Voor Willy, die houdt van miniaturen, hebben we een mini trommeltje gemaakt. Veel plezier ermee&#8230;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"720\" height=\"540\" src=\"http:\/\/www.tamboerke.nl\/wp-content\/uploads\/2020\/09\/118619998_2116377645173704_7171132188657694574_o.jpg\" alt=\"\" class=\"wp-image-392\" srcset=\"http:\/\/www.tamboerke.nl\/wp-content\/uploads\/2020\/09\/118619998_2116377645173704_7171132188657694574_o.jpg 720w, http:\/\/www.tamboerke.nl\/wp-content\/uploads\/2020\/09\/118619998_2116377645173704_7171132188657694574_o-300x225.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>We hebben 2 trommen, 1 senior en 1 junior, gerestaureerd voor het Gilde St.Antonius St.Sebastiaan uit Udenhout. Voor Willy, die houdt van miniaturen, hebben we een mini trommeltje gemaakt. Veel plezier ermee&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.tamboerke.nl\/index.php\/wp-json\/wp\/v2\/posts\/391"}],"collection":[{"href":"http:\/\/www.tamboerke.nl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.tamboerke.nl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.tamboerke.nl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.tamboerke.nl\/index.php\/wp-json\/wp\/v2\/comments?post=391"}],"version-history":[{"count":1,"href":"http:\/\/www.tamboerke.nl\/index.php\/wp-json\/wp\/v2\/posts\/391\/revisions"}],"predecessor-version":[{"id":393,"href":"http:\/\/www.tamboerke.nl\/index.php\/wp-json\/wp\/v2\/posts\/391\/revisions\/393"}],"wp:attachment":[{"href":"http:\/\/www.tamboerke.nl\/index.php\/wp-json\/wp\/v2\/media?parent=391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.tamboerke.nl\/index.php\/wp-json\/wp\/v2\/categories?post=391"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.tamboerke.nl\/index.php\/wp-json\/wp\/v2\/tags?post=391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}